{"id":2141,"date":"2024-07-14T09:47:16","date_gmt":"2024-07-14T09:47:16","guid":{"rendered":"https:\/\/vpm.company\/?page_id=2141"},"modified":"2024-07-14T09:47:50","modified_gmt":"2024-07-14T09:47:50","slug":"quotation","status":"publish","type":"page","link":"https:\/\/vpm.company\/en\/quotation\/","title":{"rendered":"Quotation"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2141\" class=\"elementor elementor-2141\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c3f12fb e-flex e-con-boxed e-con e-parent\" data-id=\"c3f12fb\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b727888 elementor-widget elementor-widget-wpforms\" data-id=\"b727888\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style id=\"wpforms-css-vars-root\">\n\t\t\t\t:root {\n\t\t\t\t\t--wpforms-field-border-radius: 3px;\n--wpforms-field-background-color: #ffffff;\n--wpforms-field-border-color: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-text-color: rgba( 0, 0, 0, 0.7 );\n--wpforms-label-color: rgba( 0, 0, 0, 0.85 );\n--wpforms-label-sublabel-color: rgba( 0, 0, 0, 0.55 );\n--wpforms-label-error-color: #d63637;\n--wpforms-button-border-radius: 3px;\n--wpforms-button-background-color: #066aab;\n--wpforms-button-text-color: #ffffff;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\n\t\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-2138\"><form id=\"wpforms-form-2138\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"2138\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/2141\" data-token=\"52d5c9d14e788066e666674c5badf741\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/2141\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-2138-field_1-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-2138-field_1\" aria-hidden=\"false\">Layout<\/label><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-50-50\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-2138-field_2-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-2138-field_2\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2138-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-2138-field_2-error\" required><\/div><div id=\"wpforms-2138-field_4-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-2138-field_4\">Phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-2138-field_4\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][4]\" aria-errormessage=\"wpforms-2138-field_4-error\" required><\/div><div id=\"wpforms-2138-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-2138-field_6\">Location - City <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2138-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-2138-field_6-error\" required><\/div><div id=\"wpforms-2138-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-2138-field_8\">Event Nature <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2138-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" aria-errormessage=\"wpforms-2138-field_8-error\" required><\/div><div id=\"wpforms-2138-field_10-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-2138-field_10\">How many days do you expect the event to take place?  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2138-field_10\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][10]\" aria-errormessage=\"wpforms-2138-field_10-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-2138-field_3-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-2138-field_3\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-2138-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" spellcheck=\"false\" aria-errormessage=\"wpforms-2138-field_3-error\" required><\/div><div id=\"wpforms-2138-field_5-container\" class=\"wpforms-field wpforms-field-url\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-2138-field_5\">Website \/ URL<\/label><input type=\"url\" id=\"wpforms-2138-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\" aria-errormessage=\"wpforms-2138-field_5-error\" ><\/div><div id=\"wpforms-2138-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-2138-field_7\">Company Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2138-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-2138-field_7-error\" required><\/div><div id=\"wpforms-2138-field_9-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-2138-field_9\">location - where will the event be at <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2138-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" aria-errormessage=\"wpforms-2138-field_9-error\" required><\/div><div id=\"wpforms-2138-field_11-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-2138-field_11\">Number of guests expected to come <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2138-field_11\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][11]\" aria-errormessage=\"wpforms-2138-field_11-error\" required><\/div><\/div><\/div><\/div><\/div><!-- .wpforms-field-container --><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"2138\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"26\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-2138\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img decoding=\"async\" src=\"https:\/\/vpm.company\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":26,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2141","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/vpm.company\/en\/wp-json\/wp\/v2\/pages\/2141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vpm.company\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vpm.company\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vpm.company\/en\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/vpm.company\/en\/wp-json\/wp\/v2\/comments?post=2141"}],"version-history":[{"count":4,"href":"https:\/\/vpm.company\/en\/wp-json\/wp\/v2\/pages\/2141\/revisions"}],"predecessor-version":[{"id":2145,"href":"https:\/\/vpm.company\/en\/wp-json\/wp\/v2\/pages\/2141\/revisions\/2145"}],"wp:attachment":[{"href":"https:\/\/vpm.company\/en\/wp-json\/wp\/v2\/media?parent=2141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}